{"id":2405,"date":"2023-10-30T12:48:19","date_gmt":"2023-10-30T12:48:19","guid":{"rendered":"https:\/\/hamraheroes.org\/?post_type=testimonial&#038;p=2405"},"modified":"2023-11-14T17:03:58","modified_gmt":"2023-11-14T17:03:58","slug":"jennifer-wilson","status":"publish","type":"testimonial","link":"https:\/\/hamraheroes.org\/pt\/testimonial\/jennifer-wilson\/","title":{"rendered":"JENNIFER WILSON"},"content":{"rendered":"<p>Eu estava na empresa h\u00e1 menos de 6 meses quando comecei a pedir ajuda. Eu estava em uma situa\u00e7\u00e3o de viol\u00eancia dom\u00e9stica muito grave em casa e n\u00e3o tinha a quem recorrer. Vim trabalhar para escapar porque sabia que naquelas horas eu estava segura e meus filhos tamb\u00e9m. Fiquei tanto tempo porque n\u00e3o tinha recursos para ir a outro lugar e manter um teto sobre a cabe\u00e7a deles era o objetivo mais importante. Minhas liga\u00e7\u00f5es telef\u00f4nicas eram monitoradas, o dinheiro era rastreado, eu estava perdida. Na \u00e9poca, meu gerente geral me falou sobre o HERO Fund e, assim que fiz a solicita\u00e7\u00e3o, recebi o cheque em quest\u00e3o de dias. Pude sair de casa, mudar para um lugar seguro e come\u00e7ar uma nova vida com tudo isso para tr\u00e1s. N\u00e3o precisei me explorar no processo, n\u00e3o precisei implorar por ajuda... implorar para que algu\u00e9m acreditasse em mim.  Bastou uma simples etapa de inscri\u00e7\u00e3o e uma conversa por telefone e minha vida literalmente mudou. Eu n\u00e3o estaria onde estou hoje sem essa ajuda, e, para falar a verdade, provavelmente n\u00e3o estaria vivo sem essa ajuda. Ficarei para sempre em d\u00edvida com o HERO Fund por ter feito uma diferen\u00e7a t\u00e3o grande em minha fam\u00edlia e em nossas vidas.<\/p>\n<p>Jennifer Wilson, Gerente Geral, Wendy\u2019s do Missouri<\/p>","protected":false},"featured_media":2607,"template":"","class_list":["post-2405","testimonial","type-testimonial","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/hamraheroes.org\/pt\/wp-json\/wp\/v2\/testimonial\/2405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hamraheroes.org\/pt\/wp-json\/wp\/v2\/testimonial"}],"about":[{"href":"https:\/\/hamraheroes.org\/pt\/wp-json\/wp\/v2\/types\/testimonial"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hamraheroes.org\/pt\/wp-json\/wp\/v2\/media\/2607"}],"wp:attachment":[{"href":"https:\/\/hamraheroes.org\/pt\/wp-json\/wp\/v2\/media?parent=2405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}