{"id":2450,"date":"2023-11-06T12:46:03","date_gmt":"2023-11-06T12:46:03","guid":{"rendered":"https:\/\/hamraheroes.org\/?page_id=2450"},"modified":"2026-02-19T17:40:10","modified_gmt":"2026-02-19T17:40:10","slug":"frequently-asked-questions","status":"publish","type":"page","link":"https:\/\/hamraheroes.org\/es\/frequently-asked-questions\/","title":{"rendered":"Preguntas frecuentes"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-custom-z-index\" style=\"--link_hover_color: var(--awb-color5);--link_color: var(--awb-color8);--awb-border-color:hsla(var(--awb-color3-h),var(--awb-color3-s),calc(var(--awb-color3-l) + 10%),var(--awb-color3-a));--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-z-index:9999;--awb-padding-top:15px;--awb-padding-bottom:15px;--awb-background-color:var(--awb-color1);--awb-flex-wrap:wrap;--awb-box-shadow:0px 2px 7px 0px hsla(var(--awb-color8-h),var(--awb-color8-s),var(--awb-color8-l),calc(var(--awb-color8-a) - 93%));\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column fusion-flex-align-self-flex-start fusion-column-no-min-height fusion-animated\" style=\"--awb-padding-top:20px;--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-animationtype=\"fadeIn\" data-animationduration=\"0.8\" data-animationoffset=\"top-into-view\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-center fusion-content-layout-row\"><div class=\"fusion-title title fusion-title-1 fusion-sep-none fusion-title-text fusion-title-size-two\"><h2 class=\"fusion-title-heading title-heading-left\" style=\"margin:0;\"><h1>Historias de H\u00e9roes Reales<\/h1><\/h2><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_1 1_1 fusion-flex-column fusion-flex-align-self-flex-start fusion-column-no-min-height fusion-animated\" style=\"--awb-padding-bottom:10px;--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-animationtype=\"fadeIn\" data-animationduration=\"0.8\" data-animationoffset=\"top-into-view\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-center fusion-content-layout-row\"><div class=\"fusion-text fusion-text-1\"><p>\u00a1Mira personas reales benefici\u00e1ndose del Fondo HERO!<\/p>\n<\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div style=\"text-align:center;\"><a class=\"fusion-button button-flat fusion-button-default-size button-custom fusion-button-default button-1 fusion-button-default-span fusion-button-default-type\" style=\"--button_accent_color:var(--awb-color1);--button_accent_hover_color:var(--awb-color1);--button_border_hover_color:var(--awb-color1);--button_gradient_top_color:#bf311a;--button_gradient_bottom_color:#bf311a;--button_gradient_top_color_hover:#d7513c;--button_gradient_bottom_color_hover:#d7513c;--button_padding-right:25px;--button_padding-left:25px;\" target=\"_self\" href=\"https:\/\/hamraheroes.org\/es\/testimonials\/\"><span class=\"fusion-button-text\">Ver historias<\/span><\/a><\/div><\/div><\/div><\/div><\/div>\n<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-3 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-padding-top:60px;--awb-padding-bottom:60px;--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-2 fusion-sep-none fusion-title-text fusion-title-size-four\" style=\"--awb-text-color:#bf311a;--awb-margin-top:45px;\"><h4 class=\"fusion-title-heading title-heading-left\" style=\"margin:0;\"><strong>Cobertura<\/strong><\/h4><\/div><div class=\"accordian fusion-accordian\" style=\"--awb-border-size:1px;--awb-icon-size:16px;--awb-content-font-size:var(--awb-typography4-font-size);--awb-icon-alignment:left;--awb-hover-color:var(--awb-color2);--awb-border-color:var(--awb-color3);--awb-background-color:var(--awb-color1);--awb-divider-color:var(--awb-color3);--awb-divider-hover-color:var(--awb-color3);--awb-icon-color:#ffffff;--awb-title-color:var(--awb-color8);--awb-content-color:var(--awb-color8);--awb-icon-box-color:var(--awb-color8);--awb-toggle-hover-accent-color:#a0a0a0;--awb-toggle-active-accent-color:#a0a0a0;--awb-title-font-family:var(--awb-typography1-font-family);--awb-title-font-weight:var(--awb-typography1-font-weight);--awb-title-font-style:var(--awb-typography1-font-style);--awb-title-font-size:24px;--awb-title-letter-spacing:var(--awb-typography1-letter-spacing);--awb-title-line-height:var(--awb-typography1-line-height);--awb-content-font-family:var(--awb-typography4-font-family);--awb-content-font-weight:var(--awb-typography4-font-weight);--awb-content-font-style:var(--awb-typography4-font-style);\"><div class=\"panel-group fusion-toggle-icon-boxed\" id=\"accordion-2450-1\"><div class=\"fusion-panel panel-default panel-3ad123038d77824ac fusion-toggle-has-divider\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_3ad123038d77824ac\"><a aria-expanded=\"false\" aria-controls=\"3ad123038d77824ac\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-2450-1\" data-target=\"#3ad123038d77824ac\" href=\"#3ad123038d77824ac\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">\u00bfQu\u00e9 tipos de solicitudes no cubre el fondo de emergencia?<\/span><\/a><\/h4><\/div><div id=\"3ad123038d77824ac\" class=\"panel-collapse collapse\" aria-labelledby=\"toggle_3ad123038d77824ac\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>No cubrimos con subvenciones lo siguiente: gastos m\u00e9dicos (excepto cierto equipo m\u00e9dico y enfermedades cr\u00edticas), litigios, mala planificaci\u00f3n financiera, facturas de servicios p\u00fablicos, gastos de gasolina, fianzas, embargos, licencias de maternidad u otros gastos derivados de situaciones no urgentes.<\/p>\n<p><span style=\"background-color: var(--awb-bg-color-hover); color: var(--awb-content-color); font-family: var(--awb-content-font-family); font-size: var(--awb-content-font-size); font-style: var(--awb-content-font-style); font-weight: var(--awb-content-font-weight); letter-spacing: var(--awb-content-letter-spacing); text-transform: var(--awb-content-text-transform);\">El Fondo HERO no cubre solicitudes de asistencia m\u00e9dica que ya est\u00e9n cubiertas por beneficios de salud, costos de combustible para uso vehicular o de calefacci\u00f3n en el hogar, o cualquier situaci\u00f3n que no se base en un incidente \u00fanico y no recurrente.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"fusion-title title fusion-title-3 fusion-sep-none fusion-title-text fusion-title-size-four\" style=\"--awb-text-color:#bf311a;--awb-margin-top:45px;\"><h4 class=\"fusion-title-heading title-heading-left\" style=\"margin:0;\">Solicitar ayuda<\/h4><\/div><div class=\"accordian fusion-accordian\" style=\"--awb-border-size:1px;--awb-icon-size:16px;--awb-content-font-size:var(--awb-typography4-font-size);--awb-icon-alignment:left;--awb-hover-color:var(--awb-color2);--awb-border-color:var(--awb-color3);--awb-background-color:var(--awb-color1);--awb-divider-color:var(--awb-color3);--awb-divider-hover-color:var(--awb-color3);--awb-icon-color:#ffffff;--awb-title-color:var(--awb-color8);--awb-content-color:var(--awb-color8);--awb-icon-box-color:var(--awb-color8);--awb-toggle-hover-accent-color:#a0a0a0;--awb-toggle-active-accent-color:#a0a0a0;--awb-title-font-family:var(--awb-typography1-font-family);--awb-title-font-weight:var(--awb-typography1-font-weight);--awb-title-font-style:var(--awb-typography1-font-style);--awb-title-font-size:24px;--awb-title-letter-spacing:var(--awb-typography1-letter-spacing);--awb-title-line-height:var(--awb-typography1-line-height);--awb-content-font-family:var(--awb-typography4-font-family);--awb-content-font-weight:var(--awb-typography4-font-weight);--awb-content-font-style:var(--awb-typography4-font-style);\"><div class=\"panel-group fusion-toggle-icon-boxed\" id=\"accordion-2450-2\"><div class=\"fusion-panel panel-default panel-899d3a228895914fd fusion-toggle-has-divider\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_899d3a228895914fd\"><a aria-expanded=\"false\" aria-controls=\"899d3a228895914fd\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-2450-2\" data-target=\"#899d3a228895914fd\" href=\"#899d3a228895914fd\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">\u00bfC\u00f3mo solicito una subvenci\u00f3n del Fondo HERO?<\/span><\/a><\/h4><\/div><div id=\"899d3a228895914fd\" class=\"panel-collapse collapse\" aria-labelledby=\"toggle_899d3a228895914fd\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>Los solicitantes de The HERO Fund pueden postularse en l\u00ednea en <a href=\"https:\/\/hamraheroes.org\/es\/emergency-application\/\">Solicitud de Fondo de Emergencia<\/a>.Nadie puede presentar una solicitud en nombre de un empleado, excepto en las situaciones en que un empleado haya fallecido (en este caso, un familiar puede solicitar una Subvenci\u00f3n Funeraria HERO) o en el caso de que el solicitante no pueda presentarla debido a una lesi\u00f3n f\u00edsica y haya dado permiso expreso a su supervisor o a una persona de RR. HH. para que presente la solicitud en su nombre.<\/p>\n<p>Una vez recibida una solicitud, es revisada por el equipo de administraci\u00f3n de The HERO Fund. El equipo de administraci\u00f3n de The HERO trabajar\u00e1 con el solicitante para asegurarse de que toda la documentaci\u00f3n necesaria se incluya y luego presentar\u00e1 la solicitud al Comit\u00e9 Directivo de The HERO Fund para su revisi\u00f3n y decisi\u00f3n, bas\u00e1ndose en las directrices de elegibilidad. El equipo de administraci\u00f3n de The HERO Fund se pondr\u00e1 en contacto con el solicitante si falta alg\u00fan documento necesario.<\/p>\n<p>En caso de que un solicitante no hable, lea o entienda ingl\u00e9s, dicho solicitante ser\u00e1 responsable de gestionar los servicios de traducci\u00f3n. Espec\u00edficamente, por favor designe a una persona que hable ingl\u00e9s para que se comunique en su nombre con el Equipo de Administraci\u00f3n del HERO Fund en relaci\u00f3n con su solicitud. Hay un espacio en la solicitud de emergencia del HERO Fund para incluir el nombre y la informaci\u00f3n de contacto de esa persona.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-77e7977346d40a89e fusion-toggle-has-divider\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_77e7977346d40a89e\"><a aria-expanded=\"false\" aria-controls=\"77e7977346d40a89e\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-2450-2\" data-target=\"#77e7977346d40a89e\" href=\"#77e7977346d40a89e\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">\u00bfQu\u00e9 documentaci\u00f3n se requiere?<\/span><\/a><\/h4><\/div><div id=\"77e7977346d40a89e\" class=\"panel-collapse collapse\" aria-labelledby=\"toggle_77e7977346d40a89e\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>La documentaci\u00f3n var\u00eda seg\u00fan la solicitud de subvenci\u00f3n y se requiere al momento de presentarla para ser considerada y procesar una solicitud de subvenci\u00f3n. Los administradores de HERO pueden solicitar documentaci\u00f3n adicional para apoyar el procesamiento de cualquier solicitud de subvenci\u00f3n y el solicitante tiene hasta 30 d\u00edas para proporcionar la documentaci\u00f3n para que la subvenci\u00f3n sea considerada.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-f9f9ec1fb23ae2327 fusion-toggle-has-divider\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_f9f9ec1fb23ae2327\"><a aria-expanded=\"false\" aria-controls=\"f9f9ec1fb23ae2327\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-2450-2\" data-target=\"#f9f9ec1fb23ae2327\" href=\"#f9f9ec1fb23ae2327\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">\u00bfQui\u00e9n sabr\u00e1 que he solicitado ayuda a trav\u00e9s de The HERO Fund?<\/span><\/a><\/h4><\/div><div id=\"f9f9ec1fb23ae2327\" class=\"panel-collapse collapse\" aria-labelledby=\"toggle_f9f9ec1fb23ae2327\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>Cada solicitud es administrada por el Equipo Administrativo de The HERO Fund. Cuando la solicitud se entrega al Comit\u00e9 Directivo de The HERO Fund, el nombre del solicitante no ser\u00e1 revelado. En ning\u00fan momento la informaci\u00f3n de identificaci\u00f3n del solicitante estar\u00e1 disponible para nadie involucrado en el proceso de toma de decisiones. Los administradores de The HERO Fund son las \u00fanicas personas que pueden tener acceso a la solicitud confidencial de asistencia, y dicho acceso se concede solo en la medida necesaria para procesar y financiar la solicitud, si fuera necesario.<\/p>\n<p>La solicitud del HERO Fund ofrece la opci\u00f3n para que el solicitante d\u00e9 permiso al equipo de administraci\u00f3n del HERO Fund para contactar a su Gerente General (GM) en casos donde este pueda proporcionar informaci\u00f3n para apoyar y agilizar el procesamiento de la solicitud.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-dae3c657112f07080 fusion-toggle-has-divider\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_dae3c657112f07080\"><a aria-expanded=\"false\" aria-controls=\"dae3c657112f07080\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-2450-2\" data-target=\"#dae3c657112f07080\" href=\"#dae3c657112f07080\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">\u00bfCu\u00e1nto tiempo suele tomar el proceso de solicitud\/financiamiento?<\/span><\/a><\/h4><\/div><div id=\"dae3c657112f07080\" class=\"panel-collapse collapse\" aria-labelledby=\"toggle_dae3c657112f07080\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>Normalmente, una vez que se env\u00eda una solicitud para su revisi\u00f3n en busca de financiamiento, las solicitudes se revisan dentro de 2 d\u00edas h\u00e1biles despu\u00e9s de recibir la documentaci\u00f3n y los cheques de subvenci\u00f3n se procesan el jueves despu\u00e9s de que el comit\u00e9 considera y aprueba la solicitud. Todos los cheques se enviar\u00e1n por correo a la direcci\u00f3n correspondiente a trav\u00e9s de USPS, lo que normalmente tarda 7 d\u00edas h\u00e1biles. Sin embargo, ninguna solicitud se enviar\u00e1 al Comit\u00e9 Directivo sin la documentaci\u00f3n adecuada.<\/p>\n<p>Las subvenciones m\u00e9dicas por incapacidad temporal siguen un calendario de pagos diferente, que se proporciona por correo electr\u00f3nico para todas las subvenciones m\u00e9dicas aprobadas por incapacidad temporal.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-fbf918527b3676cd4 fusion-toggle-has-divider\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_fbf918527b3676cd4\"><a aria-expanded=\"false\" aria-controls=\"fbf918527b3676cd4\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-2450-2\" data-target=\"#fbf918527b3676cd4\" href=\"#fbf918527b3676cd4\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">\u00bfQu\u00e9 sucede despu\u00e9s de haber solicitado ayuda?<\/span><\/a><\/h4><\/div><div id=\"fbf918527b3676cd4\" class=\"panel-collapse collapse\" aria-labelledby=\"toggle_fbf918527b3676cd4\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>El Comit\u00e9 Directivo del HERO Fund (compuesto por empleados que representan a todas las entidades de Hamra Enterprises) recibe una copia de la solicitud para su revisi\u00f3n (la cual no incluye ninguna informaci\u00f3n que identifique al solicitante). Este grupo tiene la important\u00edsima responsabilidad de asegurarse de que los fondos se utilicen de la manera m\u00e1s \u00fatil posible.<\/p>\n<p>Desafortunadamente, The HERO Fund no puede brindar asistencia a todos los solicitantes. El comit\u00e9 toma decisiones de asistencia bas\u00e1ndose en crisis documentadas, las pautas de elegibilidad de The HERO Fund y los estatutos que rigen al comit\u00e9. Una vez que el Comit\u00e9 Directivo de The HERO Fund haya revisado su solicitud, el Equipo Administrativo de The HERO Fund se pondr\u00e1 en contacto con usted para informarle sobre el estado de su solicitud. El comit\u00e9 puede aprobar o denegar una solicitud o solicitar informaci\u00f3n adicional. El Equipo Administrativo de The HERO Fund le indicar\u00e1 cu\u00e1l es el siguiente paso en el proceso tras la decisi\u00f3n del comit\u00e9.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"fusion-title title fusion-title-4 fusion-sep-none fusion-title-text fusion-title-size-four\" style=\"--awb-text-color:#bf311a;--awb-margin-top:45px;\"><h4 class=\"fusion-title-heading title-heading-left\" style=\"margin:0;\"><strong>Calificar para recibir ayuda<\/strong><\/h4><\/div><div class=\"accordian fusion-accordian\" style=\"--awb-border-size:1px;--awb-icon-size:16px;--awb-content-font-size:var(--awb-typography4-font-size);--awb-icon-alignment:left;--awb-hover-color:var(--awb-color2);--awb-border-color:var(--awb-color3);--awb-background-color:var(--awb-color1);--awb-divider-color:var(--awb-color3);--awb-divider-hover-color:var(--awb-color3);--awb-icon-color:#ffffff;--awb-title-color:var(--awb-color8);--awb-content-color:var(--awb-color8);--awb-icon-box-color:var(--awb-color8);--awb-toggle-hover-accent-color:#a0a0a0;--awb-toggle-active-accent-color:#a0a0a0;--awb-title-font-family:var(--awb-typography1-font-family);--awb-title-font-weight:var(--awb-typography1-font-weight);--awb-title-font-style:var(--awb-typography1-font-style);--awb-title-font-size:24px;--awb-title-letter-spacing:var(--awb-typography1-letter-spacing);--awb-title-line-height:var(--awb-typography1-line-height);--awb-content-font-family:var(--awb-typography4-font-family);--awb-content-font-weight:var(--awb-typography4-font-weight);--awb-content-font-style:var(--awb-typography4-font-style);\"><div class=\"panel-group fusion-toggle-icon-boxed\" id=\"accordion-2450-3\"><div class=\"fusion-panel panel-default panel-bede4c496b0c0c1d2 fusion-toggle-has-divider\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_bede4c496b0c0c1d2\"><a aria-expanded=\"false\" aria-controls=\"bede4c496b0c0c1d2\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-2450-3\" data-target=\"#bede4c496b0c0c1d2\" href=\"#bede4c496b0c0c1d2\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">\u00bfQui\u00e9n es elegible?<\/span><\/a><\/h4><\/div><div id=\"bede4c496b0c0c1d2\" class=\"panel-collapse collapse\" aria-labelledby=\"toggle_bede4c496b0c0c1d2\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>Empleados activos de Boston Bread, Chicago Bread, Southern Bread, Hamra Coffee, Hamra Noodles, Hamra Management, Wendy\u2019s of Chicago, Wendy\u2019s of Missouri y Wendy\u2019s of New England. Un empleado no tiene que donar al fondo para solicitar y recibir financiamiento. <\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-9f3b92b22c9412483 fusion-toggle-has-divider\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_9f3b92b22c9412483\"><a aria-expanded=\"false\" aria-controls=\"9f3b92b22c9412483\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-2450-3\" data-target=\"#9f3b92b22c9412483\" href=\"#9f3b92b22c9412483\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">\u00bfQu\u00e9 se considera una situaci\u00f3n de emergencia?<\/span><\/a><\/h4><\/div><div id=\"9f3b92b22c9412483\" class=\"panel-collapse collapse\" aria-labelledby=\"toggle_9f3b92b22c9412483\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>Los solicitantes de The HERO Fund deben tener una situaci\u00f3n de emergencia documentada que resulte en p\u00e9rdida de vida, salud o propiedad, y que se d\u00e9 en un contexto de severa dificultad financiera donde todas las dem\u00e1s fuentes de financiamiento se hayan agotado. Esta situaci\u00f3n de crisis debe ser un evento fuera del control del empleado. Las situaciones de emergencia que se consideran para recibir asistencia son:<\/p>\n<ul>\n<li>Gesti\u00f3n de deuda<\/li>\n<li>Abuso dom\u00e9stico (vivienda de transici\u00f3n)<\/li>\n<li>Gastos funerarios (debe ser financieramente responsable)<\/li>\n<li>Viaje de emergencia<\/li>\n<li>Vivienda (prevenci\u00f3n de desalojo, asistencia para reubicaci\u00f3n y\/o p\u00e9rdida total del hogar)<\/li>\n<li>M\u00e9dico (enfermedad grave, incapacidad m\u00e9dica temporal o equipo m\u00e9dico por necesidad)<\/li>\n<li>Desastre natural<\/li>\n<li>Transporte* (accidente automovil\u00edstico, reparaci\u00f3n de autom\u00f3vil, interrupci\u00f3n del transporte p\u00fablico)<\/li>\n<\/ul>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-e751f034deecbab56 fusion-toggle-has-divider\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_e751f034deecbab56\"><a aria-expanded=\"false\" aria-controls=\"e751f034deecbab56\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-2450-3\" data-target=\"#e751f034deecbab56\" href=\"#e751f034deecbab56\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">\u00bfQu\u00e9 sucede si el equipo administrativo o el comit\u00e9 directivo del HERO Fund solicita m\u00e1s informaci\u00f3n?<\/span><\/a><\/h4><\/div><div id=\"e751f034deecbab56\" class=\"panel-collapse collapse\" aria-labelledby=\"toggle_e751f034deecbab56\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>\n\t\tSi se solicita informaci\u00f3n adicional, el solicitante tendr\u00e1 30 d\u00edas para proporcionarla. Despu\u00e9s de recibir la informaci\u00f3n solicitada, la solicitud se presentar\u00e1 al Comit\u00e9 Directivo de The HERO Fund y el Equipo de Administraci\u00f3n de The HERO Fund notificar\u00e1 al solicitante el estado de la misma. Si la informaci\u00f3n solicitada no se proporciona dentro del plazo de 30 d\u00edas, la solicitud no ser\u00e1 considerada.\n\t<\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-72de3ecac875eba00 fusion-toggle-has-divider\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_72de3ecac875eba00\"><a aria-expanded=\"false\" aria-controls=\"72de3ecac875eba00\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-2450-3\" data-target=\"#72de3ecac875eba00\" href=\"#72de3ecac875eba00\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">\u00bfQu\u00e9 cantidad de financiamiento hay disponible y qu\u00e9 l\u00edmites se aplican a este financiamiento?<\/span><\/a><\/h4><\/div><div id=\"72de3ecac875eba00\" class=\"panel-collapse collapse\" aria-labelledby=\"toggle_72de3ecac875eba00\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>Dependiendo de la naturaleza de la solicitud, las subvenciones pueden variar de $100 a $2,500 para las subvenciones de eventos de emergencia elegibles y de $1,000 a $5,000 para las subvenciones de Asistencia de Reubicaci\u00f3n. (ver <a href=\"https:\/\/hamraheroes.org\/es\/what-we-do\/\" target=\"_blank\" rel=\"noopener noreferrer\">Las Directrices de Elegibilidad del Fondo HERO<\/a>. Sin embargo, un solicitante no podr\u00e1 recibir m\u00e1s de lo siguiente:<\/p>\n<p><strong>Subvenciones para eventos de emergencia<\/strong>No m\u00e1s de dos subsidios aprobados y financiados en un per\u00edodo m\u00f3vil de 12 meses.<\/p>\n<p><strong>Subsidios de vivienda<\/strong>Una subvenci\u00f3n en la vida del empleado<\/p>\n<p><b>Eventos de Transporte<\/b>: Una subvenci\u00f3n en la vida de un empleado<\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-27d40d5b6a179c421 fusion-toggle-has-divider\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_27d40d5b6a179c421\"><a aria-expanded=\"false\" aria-controls=\"27d40d5b6a179c421\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-2450-3\" data-target=\"#27d40d5b6a179c421\" href=\"#27d40d5b6a179c421\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">\u00bfQu\u00e9 pasa si mi situaci\u00f3n califica para dos directrices diferentes? (por ejemplo, Gastos funerarios y Viajes de emergencia)<\/span><\/a><\/h4><\/div><div id=\"27d40d5b6a179c421\" class=\"panel-collapse collapse\" aria-labelledby=\"toggle_27d40d5b6a179c421\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>En este caso, el solicitante completar\u00e1 dos solicitudes (una por cada directriz) y proporcionar\u00e1 la documentaci\u00f3n adecuada para cada directriz aplicable. El comit\u00e9 considerar\u00e1 cada directriz aplicable por separado. Todos los l\u00edmites siguen aplicando (ver arriba).<\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-c191e763743e24f02 fusion-toggle-has-divider\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_c191e763743e24f02\"><a aria-expanded=\"false\" aria-controls=\"c191e763743e24f02\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-2450-3\" data-target=\"#c191e763743e24f02\" href=\"#c191e763743e24f02\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">\u00bfQu\u00e9 sucede despu\u00e9s de que me aprueban la asistencia?<\/span><\/a><\/h4><\/div><div id=\"c191e763743e24f02\" class=\"panel-collapse collapse\" aria-labelledby=\"toggle_c191e763743e24f02\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>Si la solicitud es aprobada para recibir asistencia, los cheques se extender\u00e1n a nombre del solicitante. Los cheques generalmente se emiten el jueves despu\u00e9s de que el comit\u00e9 considere y apruebe el caso, y suelen tardar aproximadamente 7 d\u00edas h\u00e1biles en llegar por correo.<\/p>\n<p>En casos donde un solicitante ha sido aprobado para un subsidio m\u00e9dico por incapacidad laboral, los fondos se enviar\u00e1n al beneficiario cada dos semanas hasta que regrese al trabajo o se agote el l\u00edmite de financiaci\u00f3n, lo que ocurra primero.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-9980176df3a4176ff fusion-toggle-has-divider\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_9980176df3a4176ff\"><a aria-expanded=\"false\" aria-controls=\"9980176df3a4176ff\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-2450-3\" data-target=\"#9980176df3a4176ff\" href=\"#9980176df3a4176ff\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">\u00bfEl dinero tiene que ser devuelto?<\/span><\/a><\/h4><\/div><div id=\"9980176df3a4176ff\" class=\"panel-collapse collapse\" aria-labelledby=\"toggle_9980176df3a4176ff\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>Los fondos distribuidos son una subvenci\u00f3n, no un pr\u00e9stamo, y no necesitan ser reembolsados. Dado que el IRS considera que la asistencia es ingreso gravable, si a alg\u00fan solicitante se le otorga m\u00e1s de $2000 en asistencia, el solicitante recibir\u00e1 un formulario 1099 al final del a\u00f1o declarando la recepci\u00f3n de la subvenci\u00f3n.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-3 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-4 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-2\"><p><em>Estas Preguntas Frecuentes brindan informaci\u00f3n general sobre las operaciones del Fondo HERO. La Junta Directiva del Fondo HERO se reserva el derecho de cambiar sus pol\u00edticas y procedimientos operativos en cualquier momento de acuerdo con las disposiciones establecidas en sus estatutos. <\/em><\/p>\n<\/div><\/div><\/div><\/div><\/div><\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":2279,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"100-width.php","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-2450","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/hamraheroes.org\/es\/wp-json\/wp\/v2\/pages\/2450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hamraheroes.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hamraheroes.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hamraheroes.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hamraheroes.org\/es\/wp-json\/wp\/v2\/comments?post=2450"}],"version-history":[{"count":22,"href":"https:\/\/hamraheroes.org\/es\/wp-json\/wp\/v2\/pages\/2450\/revisions"}],"predecessor-version":[{"id":3210,"href":"https:\/\/hamraheroes.org\/es\/wp-json\/wp\/v2\/pages\/2450\/revisions\/3210"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hamraheroes.org\/es\/wp-json\/wp\/v2\/media\/2279"}],"wp:attachment":[{"href":"https:\/\/hamraheroes.org\/es\/wp-json\/wp\/v2\/media?parent=2450"}],"curies":[{"name":"wordpress","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}